{"id":1095,"count":1,"description":"","link":"http:\/\/www.eel-fotografie.de\/wp2\/tag\/autofokus\/","name":"Autofokus","slug":"autofokus","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autofokus Archive - eel-fotografie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.eel-fotografie.de\/wp2\/tag\/autofokus\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/tag\\\/autofokus\\\/\",\"url\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/tag\\\/autofokus\\\/\",\"name\":\"Autofokus Archive - eel-fotografie\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/tag\\\/autofokus\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/tag\\\/autofokus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autofokus\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/#website\",\"url\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/\",\"name\":\"eel-fotografie\",\"description\":\"fotografie - bildagentur\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/#organization\",\"name\":\"eel-fotografie | fotografie - bildagentur\",\"url\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/wp-content\\\/uploads\\\/eel-fotografie_logo_2_500x250.png\",\"contentUrl\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/wp-content\\\/uploads\\\/eel-fotografie_logo_2_500x250.png\",\"width\":500,\"height\":254,\"caption\":\"eel-fotografie | fotografie - bildagentur\"},\"image\":{\"@id\":\"http:\\\/\\\/www.eel-fotografie.de\\\/wp2\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/eelfotografie\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autofokus Archive - eel-fotografie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.eel-fotografie.de\/wp2\/tag\/autofokus\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/www.eel-fotografie.de\/wp2\/tag\/autofokus\/","url":"http:\/\/www.eel-fotografie.de\/wp2\/tag\/autofokus\/","name":"Autofokus Archive - eel-fotografie","isPartOf":{"@id":"http:\/\/www.eel-fotografie.de\/wp2\/#website"},"breadcrumb":{"@id":"http:\/\/www.eel-fotografie.de\/wp2\/tag\/autofokus\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"http:\/\/www.eel-fotografie.de\/wp2\/tag\/autofokus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.eel-fotografie.de\/wp2\/"},{"@type":"ListItem","position":2,"name":"Autofokus"}]},{"@type":"WebSite","@id":"http:\/\/www.eel-fotografie.de\/wp2\/#website","url":"http:\/\/www.eel-fotografie.de\/wp2\/","name":"eel-fotografie","description":"fotografie - bildagentur","publisher":{"@id":"http:\/\/www.eel-fotografie.de\/wp2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.eel-fotografie.de\/wp2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"http:\/\/www.eel-fotografie.de\/wp2\/#organization","name":"eel-fotografie | fotografie - bildagentur","url":"http:\/\/www.eel-fotografie.de\/wp2\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/www.eel-fotografie.de\/wp2\/#\/schema\/logo\/image\/","url":"http:\/\/www.eel-fotografie.de\/wp2\/wp-content\/uploads\/eel-fotografie_logo_2_500x250.png","contentUrl":"http:\/\/www.eel-fotografie.de\/wp2\/wp-content\/uploads\/eel-fotografie_logo_2_500x250.png","width":500,"height":254,"caption":"eel-fotografie | fotografie - bildagentur"},"image":{"@id":"http:\/\/www.eel-fotografie.de\/wp2\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/eelfotografie\/"]}]}},"_links":{"self":[{"href":"http:\/\/www.eel-fotografie.de\/wp2\/wp-json\/wp\/v2\/tags\/1095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.eel-fotografie.de\/wp2\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.eel-fotografie.de\/wp2\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.eel-fotografie.de\/wp2\/wp-json\/wp\/v2\/posts?tags=1095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}